{"id":185,"count":2,"description":"","link":"https:\/\/whisky-francais.com\/index.php\/tag\/embouteilleur-independant-2\/","name":"embouteilleur independant","slug":"embouteilleur-independant-2","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/whisky-francais.com\/index.php\/wp-json\/wp\/v2\/tags\/185"}],"collection":[{"href":"https:\/\/whisky-francais.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/whisky-francais.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/whisky-francais.com\/index.php\/wp-json\/wp\/v2\/posts?tags=185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}